{"id":18437,"date":"2023-08-03T15:27:43","date_gmt":"2023-08-03T18:27:43","guid":{"rendered":"https:\/\/sindsaudeba.org.br\/portal\/?p=18437"},"modified":"2023-08-03T15:27:43","modified_gmt":"2023-08-03T18:27:43","slug":"sindsaude-bahia-participa-do-iv-congresso-internacional-de-desastres-em-massa-em-feira-de-santana","status":"publish","type":"post","link":"https:\/\/sindsaudeba.org.br\/portal\/blog\/sindsaude-bahia-participa-do-iv-congresso-internacional-de-desastres-em-massa-em-feira-de-santana\/","title":{"rendered":"Sindsa\u00fade Bahia participa do \u00a0IV CONGRESSO INTERNACIONAL DE DESASTRES EM MASSA em Feira de Santana"},"content":{"rendered":"<p>Aconteceu na tarde de ontem (2\/08) na C\u00e2mara Municipal de Feira de Santana a audi\u00eancia p\u00fablica do \u00a0IV CONGRESSO INTERNACIONAL DE DESASTRES EM MASSA (CIDEM). A indica\u00e7\u00e3o partiu do vereador Silvio Dias.<\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-18433 aligncenter\" src=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.14.32-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.14.32-300x225.jpeg 300w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.14.32-768x576.jpeg 768w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.14.32-800x600.jpeg 800w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.14.32-700x525.jpeg 700w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.14.32.jpeg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>O IV CIDEM ocorrer\u00e1 no per\u00edodo de 23 a 26 de agosto de 2023, na Universidade Estadual de Feira de Santana.O tema deste Congresso ser\u00e1: Desastres com Inunda\u00e7\u00f5es, Barragens e Res\u00edduos T\u00f3xicos, envolvendo Produtos Perigosos (QBRN &#8211; e Qu\u00edmicos, Biol\u00f3gicos, Radioativos, Nucleares e Explosivos). Tamb\u00e9m ser\u00e3o abordados temas relacionados, atuais e de grande impacto na sociedade, como viol\u00eancia das escolas e universidades, evacua\u00e7\u00e3o, controle de p\u00e2nico e percep\u00e7\u00e3o de risco. O evento contar\u00e1 com a participa\u00e7\u00e3o de Profissionais da Sa\u00fade, Seguran\u00e7a P\u00fablica, Defesa Civil, Peritos Nacionais e Internacionais, INTERPOL, For\u00e7as Armadas, Profissionais da Ind\u00fastria, Pesquisadores e Especialistas dos diversos campos do conhecimento.<\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-18435 aligncenter\" src=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.10.31-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.10.31-300x225.jpeg 300w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.10.31-1024x768.jpeg 1024w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.10.31-768x576.jpeg 768w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.10.31-800x600.jpeg 800w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.10.31-700x525.jpeg 700w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.10.31.jpeg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>O Cidem \u00e9 um projeto humanit\u00e1rio, que visa a qualifica\u00e7\u00e3o dos profissionais, intera\u00e7\u00e3o das for\u00e7as e treinamento no sentido da promo\u00e7\u00e3o da Seguran\u00e7a P\u00fablica e prepara\u00e7\u00e3o para situa\u00e7\u00f5es de desastres em massa no pa\u00eds, com repercuss\u00e3o para a comunidade internacional.<\/p>\n<div id=\"attachment_18434\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><img aria-describedby=\"caption-attachment-18434\" loading=\"lazy\" class=\"wp-image-18434 size-medium\" src=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.11.19-300x169.jpeg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.11.19-300x169.jpeg 300w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.11.19-1024x577.jpeg 1024w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.11.19-768x432.jpeg 768w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.11.19-1536x865.jpeg 1536w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.11.19-700x394.jpeg 700w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.11.19-539x303.jpeg 539w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/WhatsApp-Image-2023-08-03-at-15.11.19.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><p id=\"caption-attachment-18434\" class=\"wp-caption-text\">Dart Clair Cerqueira &#8211; Diretora do Sindsa\u00fade Bahia<\/p><\/div>\n<p>O Sindsa\u00fade-BA e o Sintest-Ba est\u00e3o apoiando o evento e foram representados na audi\u00eancia pelas diretoras Dart Clair Cerqueira e Gisele Rocha respectivamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aconteceu na tarde de ontem (2\/08) na C\u00e2mara Municipal de Feira de Santana a audi\u00eancia p\u00fablica do \u00a0IV CONGRESSO INTERNACIONAL DE DESASTRES EM MASSA (CIDEM). A indica\u00e7\u00e3o partiu do vereador Silvio Dias. O IV CIDEM ocorrer\u00e1 no per\u00edodo de 23 a 26 de agosto de&#8230;<\/p>\n","protected":false},"author":2,"featured_media":18436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11,6],"tags":[],"amp_validity":null,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/posts\/18437"}],"collection":[{"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/comments?post=18437"}],"version-history":[{"count":1,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/posts\/18437\/revisions"}],"predecessor-version":[{"id":18438,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/posts\/18437\/revisions\/18438"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/media\/18436"}],"wp:attachment":[{"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/media?parent=18437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/categories?post=18437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/tags?post=18437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}