{"id":18381,"date":"2023-08-02T09:11:33","date_gmt":"2023-08-02T12:11:33","guid":{"rendered":"https:\/\/sindsaudeba.org.br\/portal\/?p=18381"},"modified":"2023-08-02T09:11:33","modified_gmt":"2023-08-02T12:11:33","slug":"sindsaudeba-promove-roda-de-conversa-sobre-racismo-estrutural-e-institucional-no-hospital-roberto-santos-2","status":"publish","type":"post","link":"https:\/\/sindsaudeba.org.br\/portal\/blog\/sindsaudeba-promove-roda-de-conversa-sobre-racismo-estrutural-e-institucional-no-hospital-roberto-santos-2\/","title":{"rendered":"Sindsa\u00fadeBa promove roda de conversa sobre racismo estrutural e institucional no Hospital Roberto Santos"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"size-medium wp-image-18382 alignleft\" src=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/3b941ff0-4db2-4c33-a5e0-4bf4f5a5e8fc-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/3b941ff0-4db2-4c33-a5e0-4bf4f5a5e8fc-300x225.jpg 300w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/3b941ff0-4db2-4c33-a5e0-4bf4f5a5e8fc-1024x768.jpg 1024w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/3b941ff0-4db2-4c33-a5e0-4bf4f5a5e8fc-768x576.jpg 768w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/3b941ff0-4db2-4c33-a5e0-4bf4f5a5e8fc-1536x1152.jpg 1536w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/3b941ff0-4db2-4c33-a5e0-4bf4f5a5e8fc-800x600.jpg 800w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/3b941ff0-4db2-4c33-a5e0-4bf4f5a5e8fc-700x525.jpg 700w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/3b941ff0-4db2-4c33-a5e0-4bf4f5a5e8fc.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" class=\"size-medium wp-image-18384 alignright\" src=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/61526351-0b52-42ee-a90b-846ccb9157fb-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/61526351-0b52-42ee-a90b-846ccb9157fb-300x225.jpg 300w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/61526351-0b52-42ee-a90b-846ccb9157fb-1024x768.jpg 1024w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/61526351-0b52-42ee-a90b-846ccb9157fb-768x576.jpg 768w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/61526351-0b52-42ee-a90b-846ccb9157fb-1536x1152.jpg 1536w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/61526351-0b52-42ee-a90b-846ccb9157fb-800x600.jpg 800w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/61526351-0b52-42ee-a90b-846ccb9157fb-700x525.jpg 700w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/61526351-0b52-42ee-a90b-846ccb9157fb.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" class=\"alignnone size-medium wp-image-18387\" src=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/f078e172-bdb6-4bed-9ba0-d98018457b87-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/f078e172-bdb6-4bed-9ba0-d98018457b87-300x225.jpg 300w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/f078e172-bdb6-4bed-9ba0-d98018457b87-1024x768.jpg 1024w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/f078e172-bdb6-4bed-9ba0-d98018457b87-768x576.jpg 768w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/f078e172-bdb6-4bed-9ba0-d98018457b87-1536x1152.jpg 1536w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/f078e172-bdb6-4bed-9ba0-d98018457b87-800x600.jpg 800w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/f078e172-bdb6-4bed-9ba0-d98018457b87-700x525.jpg 700w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/f078e172-bdb6-4bed-9ba0-d98018457b87.jpg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Para refletir e dialogar sobre a quest\u00e3o do racismo estrutural e institucional dentro e fora das unidades hospitalares o Sindicato dos Trabalhadores em Sa\u00fade do Estado da Bahia \u2013 Sindsa\u00fade Bahia, foi promovida, nesta ter\u00e7a-feira (01 de agosto), a roda de conversa, com tema: \u201cRacismo Estrutural e Racismo Institucional e os seus impactos na vida das mulheres negras\u201d. O evento contou com a participa\u00e7\u00e3o de especialistas a Assessora para Sa\u00fade da Popula\u00e7\u00e3o Negra \u2013 SEPROMI, Ubiraci Matilde, a diretora para Assuntos das Mulheres do Sindsa\u00fade Ba, Libiene Costaa, a ex-presidente da UBM, Nat\u00e1lia Gon\u00e7alves.<br \/>\nEstiveram presentes a presidente do Sindsa\u00fade Bahia, Ivanilda Brito, a diretora de Forma\u00e7\u00e3o e Rela\u00e7\u00f5es Inter Sindicais, Aladilce de Souza, a diretora (1\u00aa secret\u00e1ria), Maria Leonor, o tesoureiro, Dijalma Rossi, a diretora Administra\u00e7\u00e3o e Patrim\u00f4nio, Maria Celeste do Ros\u00e1rio, a diretora do Jur\u00eddico, Joana Evangelista e a diretora de Assuntos da Mulher, Libiene Costa.<br \/>\nNa abertura, a Maria Celest indagou o p\u00fablico, &#8220;O racismo mora em mim?&#8221;, provocando a reflex\u00e3o de todos(as). Puxando a tem\u00e1tica e abrindo oficialmente a roda, a presidente Ivanilda Brito, pontuou sobre os anos de explora\u00e7\u00e3o e a constante \u201cinvisibiliza\u00e7\u00e3o\u201d da popula\u00e7\u00e3o negra e a necessidade de reconhecimento, responsabiliza\u00e7\u00e3o e repara\u00e7\u00e3o da escravid\u00e3o e das atitudes racistas do Estado brasileiro.<br \/>\nA diretora intersindical, Aladilce de Souza, que sempre questionou sobre o racismo no servi\u00e7o p\u00fablico pontuou. &#8220;Quando olhamos a quest\u00e3o da escravid\u00e3o da popula\u00e7\u00e3o negra, vemos que falhamos enquanto sociedade. Primeiro porque h\u00e1 um grande desconhecimento sobre a escravid\u00e3o as lutas hist\u00f3ricas e relembrou o quanto lutaram nas unidades hospitalares por respeito e garantir os direitos dos servidores p\u00fablicos\u201d.<\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-18385 alignleft\" src=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/d270a9e8-79aa-4e18-84b9-b9ba00a5e59f-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/d270a9e8-79aa-4e18-84b9-b9ba00a5e59f-225x300.jpg 225w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/d270a9e8-79aa-4e18-84b9-b9ba00a5e59f-768x1024.jpg 768w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/d270a9e8-79aa-4e18-84b9-b9ba00a5e59f-1152x1536.jpg 1152w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/d270a9e8-79aa-4e18-84b9-b9ba00a5e59f-600x800.jpg 600w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/d270a9e8-79aa-4e18-84b9-b9ba00a5e59f-700x933.jpg 700w, https:\/\/sindsaudeba.org.br\/portal\/wp-content\/uploads\/2023\/08\/d270a9e8-79aa-4e18-84b9-b9ba00a5e59f.jpg 1200w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Com uma apresenta\u00e7\u00e3o hist\u00f3rica sobre o racismo no Estado e como surgiu as primeiras a\u00e7\u00f5es na defesa dos\u00a0\u00a0negros,\u00a0a professora Ubiraci, abre a fala com um questionamento importante: \u201cTodos iguais perante a lei\u201d \u2013 ela, abordou a necessidade de uma luta constante contra o racismo. Para a professora Ubiraci Matilde, o racismo precisa ser tratado nas dimens\u00f5es institucional e estrutural. &#8220;S\u00f3 avan\u00e7aremos quando pararmos de tratar o racismo como um problema alheio&#8221;, afirmou.<\/p>\n<p>Para a ex-presidente da UBM, Nat\u00e1lia Gon\u00e7alves, o pior racismo \u00e9 o que mora no cotidiano, no que se pratica e n\u00e3o se percebe. Segundo ela, duas raz\u00f5es agravam o problema: a primeira \u00e9 que ele \u00e9 velado; a segunda \u00e9 que a sociedade \u00e9 baseada em uma rede de privil\u00e9gios. &#8220;Temos muita gente que n\u00e3o possui as mesmas oportunidades. Entender o racismo \u00e9 perceber como o outro e como voc\u00ea mesmo o reproduzem sem pensar&#8221;, acrescentou.<br \/>\nNo entender da a Assessora para Sa\u00fade da Popula\u00e7\u00e3o Negra \u2013 SEPROMI, Ubiraci Matilde, o Brasil conseguir\u00e1 pagar sua d\u00edvida com a popula\u00e7\u00e3o negra quando cumprir a constitui\u00e7\u00e3o Federal, que pontual uma sociedade justa, fraterna e solid\u00e1ria. &#8220;Em 13 de maio de 1888, a escravid\u00e3o foi abolida, ali nasceu a discrimina\u00e7\u00e3o. Precisamos lutar todos os dias contra o racismo e pela igualdade de oportunidade, pois todos s\u00e3o iguais perante a lei, sem distin\u00e7\u00e3o&#8221;, finalizou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para refletir e dialogar sobre a quest\u00e3o do racismo estrutural e institucional dentro e fora das unidades hospitalares o Sindicato dos Trabalhadores em Sa\u00fade do Estado da Bahia \u2013 Sindsa\u00fade Bahia, foi promovida, nesta ter\u00e7a-feira (01 de agosto), a roda de conversa, com tema: \u201cRacismo&#8230;<\/p>\n","protected":false},"author":2,"featured_media":18393,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[11,6,7],"tags":[260,517,513],"amp_validity":null,"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/posts\/18381"}],"collection":[{"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/comments?post=18381"}],"version-history":[{"count":1,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/posts\/18381\/revisions"}],"predecessor-version":[{"id":18398,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/posts\/18381\/revisions\/18398"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/media\/18393"}],"wp:attachment":[{"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/media?parent=18381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/categories?post=18381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sindsaudeba.org.br\/portal\/wp-json\/wp\/v2\/tags?post=18381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}